{"id":9866,"date":"2024-05-02T08:00:00","date_gmt":"2024-05-02T14:00:00","guid":{"rendered":"https:\/\/www.cosmos.com.mx\/blog\/?p=9866"},"modified":"2024-04-25T14:58:17","modified_gmt":"2024-04-25T20:58:17","slug":"productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria","status":"publish","type":"post","link":"https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/","title":{"rendered":"Productos Nonwoven, una nueva generaci\u00f3n ecol\u00f3gica en material para la industria"},"content":{"rendered":"\n<p>Los <a href=\"https:\/\/productos-nonwoven.com\/\">productos nonwoven<\/a> en el mercado han tenido un gran \u00e9xito, debido a los beneficios de su material \u201cno tejido\u201d y las propiedades que lo acompa\u00f1an como su resistencia a la humedad, y que es transpirable, flexible, liviano, ign\u00edfugo y sustentable. Adem\u00e1s, el nonwoven ofrece:<\/p>\n\n\n\n<!--more-->\n\n\n\n<ul>\n<li>Costos reducidos: Suele ser m\u00e1s econ\u00f3mico que otros materiales.<\/li>\n\n\n\n<li>Mayor eficiencia: Su f\u00e1cil manipulaci\u00f3n y versatilidad aumenta su adaptaci\u00f3n a los procesos de producci\u00f3n.<\/li>\n\n\n\n<li>Calidad garantizada: Los productos nonwoven cumplen con altos est\u00e1ndares de calidad y normativas espec\u00edficas de cada industria.<\/li>\n\n\n\n<li>Sostenibilidad: Los productos hechos con nonwoven son reciclables y contribuyen a la reducci\u00f3n de residuos.<\/li>\n<\/ul>\n\n\n\n<p>El punto de la sostenibilidad es actualmente de m\u00e1ximo inter\u00e9s en las industrias que buscan materiales m\u00e1s amigables con el medio ambiente que apoyen sus certificaciones, pero que tambi\u00e9n les generen ahorros y mayor proyecci\u00f3n con el consumidor final, por lo que te presentamos estos atributos en los <a href=\"https:\/\/productos-nonwoven.com\/\">productos nonwoven<\/a>.<\/p>\n\n\n\n<h2>\u00bfPorqu\u00e9 es ecol\u00f3gico el nonwoven?<\/h2>\n\n\n\n<p>Te compartimos algunas razones por las que el nonwoven es considerado un material ecol\u00f3gico:<\/p>\n\n\n\n<p><strong>1. Sostenibilidad.<\/strong> El nonwoven se produce utilizando t\u00e9cnicas de fabricaci\u00f3n que requieren menos energ\u00eda y agua en comparaci\u00f3n con otros materiales. Adem\u00e1s, se puede fabricar con fibras recicladas, para no hacer uso de m\u00e1s recursos.<\/p>\n\n\n\n<p><strong>2. Biodegradabilidad.<\/strong> El nonwoven es un material biodegradable, lo que significa que se descompone de manera natural en el medio ambiente sin dejar residuos t\u00f3xicos. Esto es importante en un momento en el que la gesti\u00f3n de residuos se ha convertido en un desaf\u00edo global.<\/p>\n\n\n\n<p><strong>3. Reducci\u00f3n de residuos.<\/strong> El nonwoven se utiliza en una amplia gama de productos que reemplazan a otros materiales desechables. Por ejemplo, se utiliza en bolsas reutilizables en lugar de bolsas de pl\u00e1stico de un solo uso.<\/p>\n\n\n\n<p><strong>4. Eficiencia energ\u00e9tica<\/strong>. El proceso de fabricaci\u00f3n del nonwoven requiere menos energ\u00eda en comparaci\u00f3n con otros materiales. Adem\u00e1s, su ligereza y capacidad de aislamiento t\u00e9rmico ayudan a reducir el consumo de energ\u00eda en aplicaciones como la construcci\u00f3n y la industria automotriz.<\/p>\n\n\n\n<p><strong>5. Versatilidad y durabilidad.<\/strong> El nonwoven es un material altamente vers\u00e1til que se puede utilizar en una amplia gama de aplicaciones en una sola industria, por ejemplo, en la industria del mueble, act\u00faa como material de embalaje y material de fabricaci\u00f3n, igual que en el sector automotriz.<\/p>\n\n\n\n<h2>\u00bfQu\u00e9 industrias ya procesan o utilizan productos nonwoven ecol\u00f3gicos?<\/h2>\n\n\n\n<ul>\n<li>Industria m\u00e9dica: <a href=\"https:\/\/productos-nonwoven.com\/\">productos nonwoven<\/a> sanitarios, batas quir\u00fargicas, mascarillas, gorros, entre otros.<\/li>\n\n\n\n<li>Industria de la higiene: pa\u00f1ales, toallas sanitarias, productos de cuidado personal.<\/li>\n\n\n\n<li>Industria automotriz: revestimientos de asientos, paneles de puertas, filtros de aire.<\/li>\n\n\n\n<li>Industria agr\u00edcola: <a href=\"https:\/\/productos-nonwoven.com\/\">productos nonwoven<\/a> como mallas para protecci\u00f3n de cultivos, geotextiles.<\/li>\n\n\n\n<li>Industria de la construcci\u00f3n: aislantes t\u00e9rmicos y ac\u00fasticos, membranas impermeabilizantes.<\/li>\n\n\n\n<li>Industria de embalaje: bolsas reutilizables, empaques protectores<\/li>\n<\/ul>\n\n\n\n<p>Si est\u00e1s interesado en utilizar <a href=\"https:\/\/productos-nonwoven.com\/\">productos nonwove<\/a>n, no dudes en solicitar una cotizaci\u00f3n a nuestros proveedores aqu\u00ed.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El punto de la sostenibilidad es actualmente de m\u00e1ximo inter\u00e9s en las industrias que buscan materiales m\u00e1s amigables con el medio ambiente que apoyen sus certificaciones, pero que tambi\u00e9n les generen ahorros y mayor proyecci\u00f3n con el consumidor final, por lo que te presentamos estos atributos en los productos nonwoven.<\/p>\n","protected":false},"author":32,"featured_media":9867,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"categories":[1424],"tags":[562,1967,1966],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Productos Nonwoven, una nueva generaci\u00f3n ecol\u00f3gica en material para la industria - &quot;Tu presencia en Internet\u00ae\ufe0f te lleva por el camino de los resultados, y es una estrategia exclusiva con nosotros&quot;<\/title>\n<meta name=\"description\" content=\"El punto de la sostenibilidad es actualmente de m\u00e1ximo inter\u00e9s en las industrias que buscan materiales m\u00e1s amigables con el medio ambiente que apoyen sus certificaciones, pero que tambi\u00e9n les generen ahorros y mayor proyecci\u00f3n con el consumidor final, por lo que te presentamos estos atributos en los productos nonwoven.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Productos Nonwoven, una nueva generaci\u00f3n ecol\u00f3gica en material para la industria - &quot;Tu presencia en Internet\u00ae\ufe0f te lleva por el camino de los resultados, y es una estrategia exclusiva con nosotros&quot;\" \/>\n<meta property=\"og:description\" content=\"El punto de la sostenibilidad es actualmente de m\u00e1ximo inter\u00e9s en las industrias que buscan materiales m\u00e1s amigables con el medio ambiente que apoyen sus certificaciones, pero que tambi\u00e9n les generen ahorros y mayor proyecci\u00f3n con el consumidor final, por lo que te presentamos estos atributos en los productos nonwoven.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/\" \/>\n<meta property=\"og:site_name\" content=\"&quot;Tu presencia en Internet\u00ae\ufe0f te lleva por el camino de los resultados, y es una estrategia exclusiva con nosotros&quot;\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/CosmosOnlineB2B\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-02T14:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-25T20:58:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cosmos.com.mx\/blog\/wp-content\/uploads\/bolsas-nonwoven.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"888\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cosmos Online\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cosmos Online\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/\"},\"author\":{\"name\":\"Cosmos Online\",\"@id\":\"https:\/\/www.cosmos.com.mx\/blog\/#\/schema\/person\/13d808aeb9e0d7501405a95207ed68bc\"},\"headline\":\"Productos Nonwoven, una nueva generaci\u00f3n ecol\u00f3gica en material para la industria\",\"datePublished\":\"2024-05-02T14:00:00+00:00\",\"dateModified\":\"2024-04-25T20:58:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/\"},\"wordCount\":522,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.cosmos.com.mx\/blog\/#organization\"},\"keywords\":[\"empaque y embalaje\",\"nonwoven\",\"productos nonwoven\"],\"articleSection\":[\"Empaque y embalaje\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/\",\"url\":\"https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/\",\"name\":\"Productos Nonwoven, una nueva generaci\u00f3n ecol\u00f3gica en material para la industria - &quot;Tu presencia en Internet\u00ae\ufe0f te lleva por el camino de los resultados, y es una estrategia exclusiva con nosotros&quot;\",\"isPartOf\":{\"@id\":\"https:\/\/www.cosmos.com.mx\/blog\/#website\"},\"datePublished\":\"2024-05-02T14:00:00+00:00\",\"dateModified\":\"2024-04-25T20:58:17+00:00\",\"description\":\"El punto de la sostenibilidad es actualmente de m\u00e1ximo inter\u00e9s en las industrias que buscan materiales m\u00e1s amigables con el medio ambiente que apoyen sus certificaciones, pero que tambi\u00e9n les generen ahorros y mayor proyecci\u00f3n con el consumidor final, por lo que te presentamos estos atributos en los productos nonwoven.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.cosmos.com.mx\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empaque y embalaje\",\"item\":\"https:\/\/www.cosmos.com.mx\/blog\/category\/empaque-y-embalaje\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Productos Nonwoven, una nueva generaci\u00f3n ecol\u00f3gica en material para la industria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cosmos.com.mx\/blog\/#website\",\"url\":\"https:\/\/www.cosmos.com.mx\/blog\/\",\"name\":\"&quot;Tu presencia en Internet\u00ae\ufe0f te lleva por el camino de los resultados, y es una estrategia exclusiva con nosotros&quot;\",\"description\":\"Blog Cosmos Online*\",\"publisher\":{\"@id\":\"https:\/\/www.cosmos.com.mx\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cosmos.com.mx\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cosmos.com.mx\/blog\/#organization\",\"name\":\"COSMOS Online\",\"url\":\"https:\/\/www.cosmos.com.mx\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cosmos.com.mx\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cosmos.com.mx\/blog\/wp-content\/uploads\/logo-22-min.jpg\",\"contentUrl\":\"https:\/\/www.cosmos.com.mx\/blog\/wp-content\/uploads\/logo-22-min.jpg\",\"width\":300,\"height\":126,\"caption\":\"COSMOS Online\"},\"image\":{\"@id\":\"https:\/\/www.cosmos.com.mx\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/facebook.com\/CosmosOnlineB2B\",\"https:\/\/twitter.com\/CosmosOnlineB2B\",\"http:\/\/www.youtube.com\/user\/cosmoscanal\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cosmos.com.mx\/blog\/#\/schema\/person\/13d808aeb9e0d7501405a95207ed68bc\",\"name\":\"Cosmos Online\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cosmos.com.mx\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/438ba284a7b9656df556f91a3c7e4d3b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/438ba284a7b9656df556f91a3c7e4d3b?s=96&d=mm&r=g\",\"caption\":\"Cosmos Online\"},\"sameAs\":[\"https:\/\/twitter.com\/daniela\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Productos Nonwoven, una nueva generaci\u00f3n ecol\u00f3gica en material para la industria - &quot;Tu presencia en Internet\u00ae\ufe0f te lleva por el camino de los resultados, y es una estrategia exclusiva con nosotros&quot;","description":"El punto de la sostenibilidad es actualmente de m\u00e1ximo inter\u00e9s en las industrias que buscan materiales m\u00e1s amigables con el medio ambiente que apoyen sus certificaciones, pero que tambi\u00e9n les generen ahorros y mayor proyecci\u00f3n con el consumidor final, por lo que te presentamos estos atributos en los productos nonwoven.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/","og_locale":"es_ES","og_type":"article","og_title":"Productos Nonwoven, una nueva generaci\u00f3n ecol\u00f3gica en material para la industria - &quot;Tu presencia en Internet\u00ae\ufe0f te lleva por el camino de los resultados, y es una estrategia exclusiva con nosotros&quot;","og_description":"El punto de la sostenibilidad es actualmente de m\u00e1ximo inter\u00e9s en las industrias que buscan materiales m\u00e1s amigables con el medio ambiente que apoyen sus certificaciones, pero que tambi\u00e9n les generen ahorros y mayor proyecci\u00f3n con el consumidor final, por lo que te presentamos estos atributos en los productos nonwoven.","og_url":"https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/","og_site_name":"&quot;Tu presencia en Internet\u00ae\ufe0f te lleva por el camino de los resultados, y es una estrategia exclusiva con nosotros&quot;","article_publisher":"http:\/\/facebook.com\/CosmosOnlineB2B","article_published_time":"2024-05-02T14:00:00+00:00","article_modified_time":"2024-04-25T20:58:17+00:00","og_image":[{"width":888,"height":550,"url":"https:\/\/www.cosmos.com.mx\/blog\/wp-content\/uploads\/bolsas-nonwoven.jpg","type":"image\/jpeg"}],"author":"Cosmos Online","twitter_misc":{"Escrito por":"Cosmos Online","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/#article","isPartOf":{"@id":"https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/"},"author":{"name":"Cosmos Online","@id":"https:\/\/www.cosmos.com.mx\/blog\/#\/schema\/person\/13d808aeb9e0d7501405a95207ed68bc"},"headline":"Productos Nonwoven, una nueva generaci\u00f3n ecol\u00f3gica en material para la industria","datePublished":"2024-05-02T14:00:00+00:00","dateModified":"2024-04-25T20:58:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/"},"wordCount":522,"commentCount":0,"publisher":{"@id":"https:\/\/www.cosmos.com.mx\/blog\/#organization"},"keywords":["empaque y embalaje","nonwoven","productos nonwoven"],"articleSection":["Empaque y embalaje"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/","url":"https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/","name":"Productos Nonwoven, una nueva generaci\u00f3n ecol\u00f3gica en material para la industria - &quot;Tu presencia en Internet\u00ae\ufe0f te lleva por el camino de los resultados, y es una estrategia exclusiva con nosotros&quot;","isPartOf":{"@id":"https:\/\/www.cosmos.com.mx\/blog\/#website"},"datePublished":"2024-05-02T14:00:00+00:00","dateModified":"2024-04-25T20:58:17+00:00","description":"El punto de la sostenibilidad es actualmente de m\u00e1ximo inter\u00e9s en las industrias que buscan materiales m\u00e1s amigables con el medio ambiente que apoyen sus certificaciones, pero que tambi\u00e9n les generen ahorros y mayor proyecci\u00f3n con el consumidor final, por lo que te presentamos estos atributos en los productos nonwoven.","breadcrumb":{"@id":"https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cosmos.com.mx\/blog\/productos-nonwoven-una-nueva-generacion-ecologica-en-material-para-la-industria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cosmos.com.mx\/blog\/"},{"@type":"ListItem","position":2,"name":"Empaque y embalaje","item":"https:\/\/www.cosmos.com.mx\/blog\/category\/empaque-y-embalaje\/"},{"@type":"ListItem","position":3,"name":"Productos Nonwoven, una nueva generaci\u00f3n ecol\u00f3gica en material para la industria"}]},{"@type":"WebSite","@id":"https:\/\/www.cosmos.com.mx\/blog\/#website","url":"https:\/\/www.cosmos.com.mx\/blog\/","name":"&quot;Tu presencia en Internet\u00ae\ufe0f te lleva por el camino de los resultados, y es una estrategia exclusiva con nosotros&quot;","description":"Blog Cosmos Online*","publisher":{"@id":"https:\/\/www.cosmos.com.mx\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cosmos.com.mx\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cosmos.com.mx\/blog\/#organization","name":"COSMOS Online","url":"https:\/\/www.cosmos.com.mx\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cosmos.com.mx\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.cosmos.com.mx\/blog\/wp-content\/uploads\/logo-22-min.jpg","contentUrl":"https:\/\/www.cosmos.com.mx\/blog\/wp-content\/uploads\/logo-22-min.jpg","width":300,"height":126,"caption":"COSMOS Online"},"image":{"@id":"https:\/\/www.cosmos.com.mx\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/CosmosOnlineB2B","https:\/\/twitter.com\/CosmosOnlineB2B","http:\/\/www.youtube.com\/user\/cosmoscanal"]},{"@type":"Person","@id":"https:\/\/www.cosmos.com.mx\/blog\/#\/schema\/person\/13d808aeb9e0d7501405a95207ed68bc","name":"Cosmos Online","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cosmos.com.mx\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/438ba284a7b9656df556f91a3c7e4d3b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/438ba284a7b9656df556f91a3c7e4d3b?s=96&d=mm&r=g","caption":"Cosmos Online"},"sameAs":["https:\/\/twitter.com\/daniela"]}]}},"_links":{"self":[{"href":"https:\/\/www.cosmos.com.mx\/blog\/wp-json\/wp\/v2\/posts\/9866"}],"collection":[{"href":"https:\/\/www.cosmos.com.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cosmos.com.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cosmos.com.mx\/blog\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cosmos.com.mx\/blog\/wp-json\/wp\/v2\/comments?post=9866"}],"version-history":[{"count":1,"href":"https:\/\/www.cosmos.com.mx\/blog\/wp-json\/wp\/v2\/posts\/9866\/revisions"}],"predecessor-version":[{"id":9868,"href":"https:\/\/www.cosmos.com.mx\/blog\/wp-json\/wp\/v2\/posts\/9866\/revisions\/9868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cosmos.com.mx\/blog\/wp-json\/wp\/v2\/media\/9867"}],"wp:attachment":[{"href":"https:\/\/www.cosmos.com.mx\/blog\/wp-json\/wp\/v2\/media?parent=9866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cosmos.com.mx\/blog\/wp-json\/wp\/v2\/categories?post=9866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cosmos.com.mx\/blog\/wp-json\/wp\/v2\/tags?post=9866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}